{"id":2418,"date":"2023-06-09T15:54:46","date_gmt":"2023-06-09T15:54:46","guid":{"rendered":"https:\/\/erwesreifenberg.com\/?post_type=product&#038;p=2418"},"modified":"2023-06-10T05:38:20","modified_gmt":"2023-06-10T05:38:20","slug":"upside-down-closures-14","status":"publish","type":"product","link":"https:\/\/erwesreifenberg.com\/it\/product\/upside-down-closures-14\/","title":{"rendered":"Upside Down Closures 14"},"content":{"rendered":"<p>Upside Down Closures<\/p>","protected":false},"excerpt":{"rendered":"<p>Upside Down Closures<\/p>","protected":false},"featured_media":2412,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[27],"product_tag":[],"class_list":{"0":"post-2418","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-upside-down-closures","7":"desktop-align-left","8":"tablet-align-left","9":"mobile-align-left","10":"ast-product-gallery-layout-horizontal-slider","11":"ast-product-gallery-with-no-image","12":"ast-product-tabs-layout-horizontal","14":"first","15":"instock","16":"shipping-taxable","17":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/product\/2418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/comments?post=2418"}],"version-history":[{"count":0,"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/product\/2418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/media\/2412"}],"wp:attachment":[{"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/media?parent=2418"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/product_brand?post=2418"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/product_cat?post=2418"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/erwesreifenberg.com\/it\/wp-json\/wp\/v2\/product_tag?post=2418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}